{"id":1782,"date":"2023-01-23T12:11:34","date_gmt":"2023-01-23T11:11:34","guid":{"rendered":"https:\/\/svkirchzarten.de\/ski-nordisch\/?p=1782"},"modified":"2023-01-23T12:13:27","modified_gmt":"2023-01-23T11:13:27","slug":"svk-vereinsmeisterschaften-2023","status":"publish","type":"post","link":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/","title":{"rendered":"SVK-Vereinsmeisterschaften 2023"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]Schon vergangenen Samstag hatten die Langl\u00e4ufer des SVK Gelegenheit bei den offen ausgetragenen Vereinsmeisterschaften ihre ansteigende Form unter Beweis zu stellen.<br \/>\nDer Deutsche Skiverband hatte die Kirchzartener gebeten kurzfristig einen Deutschen Sch\u00fclercup von Finsterau zu \u00fcbernehmen.<br \/>\nDie Verantwortlichen um G\u00fcnter Huhn waren dazu auch bereit, sie erhielten vom Nordic Center daf\u00fcr jedoch nicht die Freigabe.<br \/>\nSo entschlossen sie sich kurzfristig am Samstagnachmittag die Vereinsmeisterschaften auszutragen, um den Sch\u00fclerinnen und Sch\u00fcler,<br \/>\ndie seit Juni auf ihre Wettk\u00e4mpfe hin trainieren, endlich die Gelegenheit zu bieten ihre Form f\u00fcr die anstehenden gro\u00dfen Rennen auf DSV-Ebene zu testen und Wettkampfh\u00e4rte zu erwerben.<br \/>\nDie St\u00fctzpunktsportlerinnen und \u2013sportler aus dem M\u00fcnstertal, aus Breitnau und vom Feldberg und vom Schluchsee nahmen die Einladung gerne an.<br \/>\nMit Luis Schuler (U16), Paul Tritschler, Sven Kolb (U18) sowie Jakob Horlacher und Matteo Lewe (U20) dominierten \u00fcber die 8km-Schleife die Kaderl\u00e4ufer des Baden-W\u00fcrttembergischen Nachwuchses das Renngeschehen.<br \/>\nDiese Gruppe blieb bis zur Schlussrunde dicht beisammen. Am Ende holte sich Matteo mit dem Wimpernschlag von einer Sekunde Vorsprung den Vereinspokal vor Jakob Horlacher.<\/p>\n<p>Genauso spannend gestaltete sich der Kampf um die Damenmeisterschaft. Louisa Haag (U18) platzierte sich mit 20:06.8min hauchd\u00fcnn vor Emily Weiss (U20) mit 20:07.2min und Mara Eckerle (U18) als Drittplatzierte mit 20:07.8min.<\/p>\n<p>Bei den Sch\u00fclern zeigten die U14er Hans-Peter Schuler und Elias Nkami-Hinterberger, dass sie f\u00fcr die Baden-W\u00fcrttembergischen Meisterschaften am kommenden Wochenende gut ger\u00fcstet sind<br \/>\nund dort den letztj\u00e4hrigen Titel verteidigen k\u00f6nnen. Diesmal hatte Hans-Peter Schuler knapp die Nase vorn vor Elias und ihrem Trainingsgef\u00e4hrten Hannes Maier vom SC Feldberg.<\/p>\n<p>Bei den j\u00fcngeren Sch\u00fclern U10\/11 war Theo, der Dritte aus dem Schuler-Nachwuchs, gleichfalls nicht zu schlagen.<br \/>\nEin sehr engagiertes Rennen lieferten sich in der U12 Frizzi Otto, Clara Schmidt und Zo\u00e9 Nounkoua-Hinterberger, bei dem sich Clara um den Bruchteil einer Sekunde geschlagen geben musste.<\/p>\n<p>In den Kinderklassen U7 bis U9 absolvierten 15 Jungen und M\u00e4dchen auf Fellskiern einen Hindernisparcours, den Lilly Schmidt und Anton Brandalise am schnellsten bew\u00e4ltigten.<\/p>\n<p>Fehlende Schneekilometer, die kurzfristige Terminierung, die bei den Paraweltmeisterschaften und der Universiade weilenden Mitglieder des SV K,<br \/>\nverhinderten eine noch gr\u00f6\u00dfere Teilnehmerzahl.<br \/>\nSo waren mit Tilman Horlacher und Mira Kuisle lediglich zwei am Start, die das 21. Lebensjahr \u00fcberschritten hatten.<br \/>\nBeide liefen ein so beherztes Rennen, dass sie daf\u00fcr einen gesonderten Pokal verdient gehabt h\u00e4tten.<br \/>\nAuch wenn Mira im Ziel monierte, dass diese Veranstaltung \u201enichts mehr mit einer Vereinsmeisterschaft zu tun hat \u2013 zu schnell, zu anstrengend\u201c, so zeigten sich doch alle happy \u00fcber die herrlich winterliche Atmosph\u00e4re unter Flutlicht im Nordic Center.<\/p>\n<p><em>Manfred Burghardt<\/em><\/p>\n<p><em>Foto: Toni Eckmann<\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][image_with_animation image_url=&#8220;1783&#8243; image_size=&#8220;large&#8220; animation_type=&#8220;entrance&#8220; animation=&#8220;None&#8220; animation_movement_type=&#8220;transform_y&#8220; hover_animation=&#8220;none&#8220; alignment=&#8220;&#8220; img_link_large=&#8220;yes&#8220; border_radius=&#8220;none&#8220; box_shadow=&#8220;none&#8220; image_loading=&#8220;default&#8220; max_width=&#8220;100%&#8220; max_width_mobile=&#8220;default&#8220;][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]\n<h3>Ergebnisliste zum Download:<\/h3>\n[\/vc_column_text][nectar_horizontal_list_item columns=&#8220;3&#8243; column_layout_using_3_columns=&#8220;large_first&#8220; col_1_text_align=&#8220;left&#8220; col_2_text_align=&#8220;left&#8220; col_3_text_align=&#8220;left&#8220; col_1_text_element=&#8220;p&#8220; col_2_text_element=&#8220;p&#8220; col_3_text_element=&#8220;p&#8220; cta_2_open_new_tab=&#8220;true&#8220; font_family=&#8220;p&#8220; hover_effect=&#8220;default&#8220; hover_color=&#8220;accent-color&#8220; icon_family=&#8220;none&#8220; icon_size=&#8220;regular&#8220; col_1_content=&#8220;Vereinsmeisterschaften | Ergebnisliste Klassen&#8220; col_2_content=&#8220;21.01.2023&#8243; cta_2_text=&#8220;DOWNLOAD&#8220; cta_2_url=&#8220;https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2023\/01\/21.01.23-VM-Ergebnisliste-Klassen.pdf&#8220;][nectar_horizontal_list_item columns=&#8220;3&#8243; column_layout_using_3_columns=&#8220;large_first&#8220; col_1_text_align=&#8220;left&#8220; col_2_text_align=&#8220;left&#8220; col_3_text_align=&#8220;left&#8220; col_1_text_element=&#8220;p&#8220; col_2_text_element=&#8220;p&#8220; col_3_text_element=&#8220;p&#8220; cta_2_open_new_tab=&#8220;true&#8220; font_family=&#8220;p&#8220; hover_effect=&#8220;default&#8220; hover_color=&#8220;accent-color&#8220; icon_family=&#8220;none&#8220; icon_size=&#8220;regular&#8220; col_1_content=&#8220;Vereinsmeisterschaften | Meisterliste 2023&#8243; col_2_content=&#8220;21.01.2023&#8243; cta_2_text=&#8220;DOWNLOAD&#8220; cta_2_url=&#8220;https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2023\/01\/21.01.23-VM-Meisterliste-2023.pdf&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1783,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-1782","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nordisch"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SVK-Vereinsmeisterschaften 2023 | Ski Nordisch &amp; Biathlon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SVK-Vereinsmeisterschaften 2023 | Ski Nordisch &amp; Biathlon\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Ski Nordisch &amp; Biathlon\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-23T11:11:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-23T11:13:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2023\/01\/vm2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christian Kaindl\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Kaindl\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/\"},\"author\":{\"name\":\"Christian Kaindl\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#\\\/schema\\\/person\\\/80c2f86955ce73e271cd302f7ccd3859\"},\"headline\":\"SVK-Vereinsmeisterschaften 2023\",\"datePublished\":\"2023-01-23T11:11:34+00:00\",\"dateModified\":\"2023-01-23T11:13:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/\"},\"wordCount\":1119,\"image\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/01\\\/vm2023.jpg\",\"articleSection\":[\"Nordisch\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/\",\"name\":\"SVK-Vereinsmeisterschaften 2023 | Ski Nordisch &amp; Biathlon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/01\\\/vm2023.jpg\",\"datePublished\":\"2023-01-23T11:11:34+00:00\",\"dateModified\":\"2023-01-23T11:13:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#\\\/schema\\\/person\\\/80c2f86955ce73e271cd302f7ccd3859\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/01\\\/vm2023.jpg\",\"contentUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2023\\\/01\\\/vm2023.jpg\",\"width\":768,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2023\\\/01\\\/23\\\/svk-vereinsmeisterschaften-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SV Kirchzarten\",\"item\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SVK-Vereinsmeisterschaften 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#website\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/\",\"name\":\"Ski Nordisch\",\"description\":\"\",\"alternateName\":\"SV Kirchzarten Ski Nordisch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#\\\/schema\\\/person\\\/80c2f86955ce73e271cd302f7ccd3859\",\"name\":\"Christian Kaindl\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00b03b3ba53f6adb49bbfcbe6facabc62e1e04d2f0f058a4751732f5b8997c03?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00b03b3ba53f6adb49bbfcbe6facabc62e1e04d2f0f058a4751732f5b8997c03?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00b03b3ba53f6adb49bbfcbe6facabc62e1e04d2f0f058a4751732f5b8997c03?s=96&d=mm&r=g\",\"caption\":\"Christian Kaindl\"},\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/author\\\/chris\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SVK-Vereinsmeisterschaften 2023 | Ski Nordisch &amp; Biathlon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/","og_locale":"de_DE","og_type":"article","og_title":"SVK-Vereinsmeisterschaften 2023 | Ski Nordisch &amp; Biathlon","og_description":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220;...","og_url":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/","og_site_name":"Ski Nordisch &amp; Biathlon","article_published_time":"2023-01-23T11:11:34+00:00","article_modified_time":"2023-01-23T11:13:27+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2023\/01\/vm2023.jpg","type":"image\/jpeg"}],"author":"Christian Kaindl","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Christian Kaindl","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/#article","isPartOf":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/"},"author":{"name":"Christian Kaindl","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#\/schema\/person\/80c2f86955ce73e271cd302f7ccd3859"},"headline":"SVK-Vereinsmeisterschaften 2023","datePublished":"2023-01-23T11:11:34+00:00","dateModified":"2023-01-23T11:13:27+00:00","mainEntityOfPage":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/"},"wordCount":1119,"image":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2023\/01\/vm2023.jpg","articleSection":["Nordisch"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/","url":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/","name":"SVK-Vereinsmeisterschaften 2023 | Ski Nordisch &amp; Biathlon","isPartOf":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/#primaryimage"},"image":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2023\/01\/vm2023.jpg","datePublished":"2023-01-23T11:11:34+00:00","dateModified":"2023-01-23T11:13:27+00:00","author":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#\/schema\/person\/80c2f86955ce73e271cd302f7ccd3859"},"breadcrumb":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/#primaryimage","url":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2023\/01\/vm2023.jpg","contentUrl":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2023\/01\/vm2023.jpg","width":768,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2023\/01\/23\/svk-vereinsmeisterschaften-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SV Kirchzarten","item":"https:\/\/svkirchzarten.de\/ski-nordisch\/"},{"@type":"ListItem","position":2,"name":"SVK-Vereinsmeisterschaften 2023"}]},{"@type":"WebSite","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#website","url":"https:\/\/svkirchzarten.de\/ski-nordisch\/","name":"Ski Nordisch","description":"","alternateName":"SV Kirchzarten Ski Nordisch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svkirchzarten.de\/ski-nordisch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#\/schema\/person\/80c2f86955ce73e271cd302f7ccd3859","name":"Christian Kaindl","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/00b03b3ba53f6adb49bbfcbe6facabc62e1e04d2f0f058a4751732f5b8997c03?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00b03b3ba53f6adb49bbfcbe6facabc62e1e04d2f0f058a4751732f5b8997c03?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00b03b3ba53f6adb49bbfcbe6facabc62e1e04d2f0f058a4751732f5b8997c03?s=96&d=mm&r=g","caption":"Christian Kaindl"},"url":"https:\/\/svkirchzarten.de\/ski-nordisch\/author\/chris\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 22:01:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/posts\/1782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/comments?post=1782"}],"version-history":[{"count":0,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/posts\/1782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/media\/1783"}],"wp:attachment":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/media?parent=1782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/categories?post=1782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/tags?post=1782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}