{"id":1619,"date":"2022-02-06T20:42:27","date_gmt":"2022-02-06T19:42:27","guid":{"rendered":"https:\/\/svkirchzarten.de\/ski-nordisch\/?p=1619"},"modified":"2022-02-06T20:42:50","modified_gmt":"2022-02-06T19:42:50","slug":"kinderlanglauf-in-bubenbach","status":"publish","type":"post","link":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/","title":{"rendered":"Kinderlanglauf in Bubenbach"},"content":{"rendered":"<div dir=\"auto\">\n<p>Bei sch\u00f6nstem Winterwetter und tollen Bedingungen auf der Hellewandloipe in Schw\u00e4rzenbach\u00a0trug der SC Bubenbach den 2. Kinderlanglauf des Bezirks 4 in dieser Saison aus.<\/p>\n<p>Gelaufen wurde auf einer 1 Km Runde, wobei die\u00a0Sch\u00fcler\/innen U8\/9 eine Runde liefen, die Sch\u00fcler\/innen U10\/11 zwei und die Sch\u00fcler\/innen 12 drei Kilometer.<br \/>\nDabei wurde in jeder Runde ein kleiner Slalom absolviert.<\/p>\n<p>Wir waren mit 16 Kinder vom SV Kirchzarten am Start, davon liefen\u00a0<span class=\"\">7 Sportler liefen ihren ersten Wettkampf auf Ski.<\/span><span class=\"\">\u00a0<\/span>Klassensieger wurden heute Ludwig Berlit (U9) und Theo Schuler (U10).\u00a0Silber gewannen in ihren Klassen Lilly Schmidt (U8) und Nele Dupp\u00e9 (U9).\u00a0Skadi Rombach (U8) und Tiago Rencker (U9) liefen als 4. Platzierte knapp am Podest vorbei.<br \/>\nAuf der kindgerechten, toll pr\u00e4parierten Strecke hatten alle ihren Spa\u00df.<\/p>\n<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">\n<p>Unsere U11 M\u00e4dels konnten heute einen 3-fach Sieg herauslaufen!<\/p>\n<\/div>\n<div dir=\"auto\">\n<div class=\"WordSection1\">\n<div class=\"\">Gratulation an die Neulinge und viel Freude und weiterhin Erfolg f\u00fcr unseren Nachwuchs!<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bei sch\u00f6nstem Winterwetter und tollen Bedingungen auf der Hellewandloipe in&#8230;<\/p>\n","protected":false},"author":16,"featured_media":1616,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,4],"tags":[],"class_list":{"0":"post-1619","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-allgemein","8":"category-nordisch"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kinderlanglauf in Bubenbach | Ski Nordisch &amp; Biathlon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kinderlanglauf in Bubenbach | Ski Nordisch &amp; Biathlon\" \/>\n<meta property=\"og:description\" content=\"Bei sch\u00f6nstem Winterwetter und tollen Bedingungen auf der Hellewandloipe in...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/\" \/>\n<meta property=\"og:site_name\" content=\"Ski Nordisch &amp; Biathlon\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-06T19:42:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-06T19:42:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2022\/02\/IMG_3666-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nordisch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"nordisch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/\"},\"author\":{\"name\":\"nordisch\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#\\\/schema\\\/person\\\/485866d97cfeb0ab6cb43d31f57bc682\"},\"headline\":\"Kinderlanglauf in Bubenbach\",\"datePublished\":\"2022-02-06T19:42:27+00:00\",\"dateModified\":\"2022-02-06T19:42:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/\"},\"wordCount\":154,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/02\\\/IMG_3666-scaled.jpg\",\"articleSection\":{\"1\":\"Nordisch\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/\",\"name\":\"Kinderlanglauf in Bubenbach | Ski Nordisch &amp; Biathlon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/02\\\/IMG_3666-scaled.jpg\",\"datePublished\":\"2022-02-06T19:42:27+00:00\",\"dateModified\":\"2022-02-06T19:42:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#\\\/schema\\\/person\\\/485866d97cfeb0ab6cb43d31f57bc682\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/02\\\/IMG_3666-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2022\\\/02\\\/IMG_3666-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/2022\\\/02\\\/06\\\/kinderlanglauf-in-bubenbach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SV Kirchzarten\",\"item\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kinderlanglauf in Bubenbach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#website\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/\",\"name\":\"Ski Nordisch\",\"description\":\"\",\"alternateName\":\"SV Kirchzarten Ski Nordisch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#\\\/schema\\\/person\\\/485866d97cfeb0ab6cb43d31f57bc682\",\"name\":\"nordisch\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d058a53f620f46414fc06f2ef8ecfb7631964ca6096ae6786cac8414a1af8bb2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d058a53f620f46414fc06f2ef8ecfb7631964ca6096ae6786cac8414a1af8bb2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d058a53f620f46414fc06f2ef8ecfb7631964ca6096ae6786cac8414a1af8bb2?s=96&d=mm&r=g\",\"caption\":\"nordisch\"},\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/author\\\/nordisch\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kinderlanglauf in Bubenbach | Ski Nordisch &amp; Biathlon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/","og_locale":"de_DE","og_type":"article","og_title":"Kinderlanglauf in Bubenbach | Ski Nordisch &amp; Biathlon","og_description":"Bei sch\u00f6nstem Winterwetter und tollen Bedingungen auf der Hellewandloipe in...","og_url":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/","og_site_name":"Ski Nordisch &amp; Biathlon","article_published_time":"2022-02-06T19:42:27+00:00","article_modified_time":"2022-02-06T19:42:50+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2022\/02\/IMG_3666-scaled.jpg","type":"image\/jpeg"}],"author":"nordisch","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"nordisch","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/#article","isPartOf":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/"},"author":{"name":"nordisch","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#\/schema\/person\/485866d97cfeb0ab6cb43d31f57bc682"},"headline":"Kinderlanglauf in Bubenbach","datePublished":"2022-02-06T19:42:27+00:00","dateModified":"2022-02-06T19:42:50+00:00","mainEntityOfPage":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/"},"wordCount":154,"commentCount":0,"image":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/#primaryimage"},"thumbnailUrl":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2022\/02\/IMG_3666-scaled.jpg","articleSection":{"1":"Nordisch"},"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/","url":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/","name":"Kinderlanglauf in Bubenbach | Ski Nordisch &amp; Biathlon","isPartOf":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/#primaryimage"},"image":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/#primaryimage"},"thumbnailUrl":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2022\/02\/IMG_3666-scaled.jpg","datePublished":"2022-02-06T19:42:27+00:00","dateModified":"2022-02-06T19:42:50+00:00","author":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#\/schema\/person\/485866d97cfeb0ab6cb43d31f57bc682"},"breadcrumb":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/#primaryimage","url":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2022\/02\/IMG_3666-scaled.jpg","contentUrl":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-content\/uploads\/sites\/24\/2022\/02\/IMG_3666-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/2022\/02\/06\/kinderlanglauf-in-bubenbach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SV Kirchzarten","item":"https:\/\/svkirchzarten.de\/ski-nordisch\/"},{"@type":"ListItem","position":2,"name":"Kinderlanglauf in Bubenbach"}]},{"@type":"WebSite","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#website","url":"https:\/\/svkirchzarten.de\/ski-nordisch\/","name":"Ski Nordisch","description":"","alternateName":"SV Kirchzarten Ski Nordisch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svkirchzarten.de\/ski-nordisch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#\/schema\/person\/485866d97cfeb0ab6cb43d31f57bc682","name":"nordisch","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/d058a53f620f46414fc06f2ef8ecfb7631964ca6096ae6786cac8414a1af8bb2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d058a53f620f46414fc06f2ef8ecfb7631964ca6096ae6786cac8414a1af8bb2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d058a53f620f46414fc06f2ef8ecfb7631964ca6096ae6786cac8414a1af8bb2?s=96&d=mm&r=g","caption":"nordisch"},"url":"https:\/\/svkirchzarten.de\/ski-nordisch\/author\/nordisch\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:42:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/posts\/1619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/comments?post=1619"}],"version-history":[{"count":0,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/posts\/1619\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/media\/1616"}],"wp:attachment":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/media?parent=1619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/categories?post=1619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/tags?post=1619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}