{"id":60,"date":"2019-11-07T11:28:50","date_gmt":"2019-11-07T10:28:50","guid":{"rendered":"https:\/\/svkirchzarten.de\/ski-nordisch\/?page_id=60"},"modified":"2019-11-20T10:34:30","modified_gmt":"2019-11-20T09:34:30","slug":"unternehmen","status":"publish","type":"page","link":"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/","title":{"rendered":"Unternehmen"},"content":{"rendered":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; background_image=&#8220;10&#8243; enable_bg_scale=&#8220;true&#8220; column_shadow=&#8220;none&#8220; width=&#8220;1\/2&#8243; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][\/vc_column][vc_column column_padding=&#8220;padding-10-percent&#8220; column_padding_position=&#8220;all&#8220; background_color=&#8220;#ffffff&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_shadow=&#8220;none&#8220; width=&#8220;1\/2&#8243; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_row_inner column_margin=&#8220;default&#8220; text_align=&#8220;left&#8220;][vc_column_inner enable_animation=&#8220;true&#8220; animation=&#8220;fade-in-from-bottom&#8220; column_padding=&#8220;no-extra-padding&#8220; column_padding_position=&#8220;all&#8220; background_color_opacity=&#8220;1&#8243; width=&#8220;1\/1&#8243; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_custom_heading text=&#8220;Teambuilding &amp; Schneeerfahrung&#8220; font_container=&#8220;tag:h5|text_align:left|color:%23bfbfbf&#8220; use_theme_fonts=&#8220;yes&#8220; css=&#8220;.vc_custom_1573634255510{margin-bottom: 10px !important;}&#8220;][vc_custom_heading text=&#8220;Langlaufevents f\u00fcr Unternehmen&#8220; font_container=&#8220;tag:h2|font_size:40|text_align:left|line_height:50px&#8220; use_theme_fonts=&#8220;yes&#8220;][vc_custom_heading text=&#8220;Egal, ob Weihnachtsfeier, Teamevent, Betriebsausflug oder Klassenausflug, unsere lizensierten, hochqualifizierten und erfahrenen Trainer begleiten Ihr pers\u00f6nliches Anliegen zum Erfolg und vermitteln Einblicke in Techniktraining und teambildende Ma\u00dfnahmen. Gemeinsam Zeit im Schnee zu verbringen, alle auf einem Leistungsstand und sich gegenseitig st\u00fctzend zum Erfolg zu begleiten ist eine Erfahrung der besonderen Art. R\u00fccksicht, Geduld und Freude verbinden.<br \/>\nGemeinsame Zeit, die lange in Erinnerung bleibt.<\/p>\n<p>Gerne unterbreiten wir Ihnen hier ein individuelles und auf Sie zugeschnittenes Angebot \u2013 fragen Sie uns unverbindlich an.<\/p>\n<p>Ihr Ansprechpartner ist Sven Buchheister<br \/>\nTelefonisch zu erreichen unter 0049 163 777 6532 oder per E-Mail: svenbuchheister(at)yahoo.com&#8220; font_container=&#8220;tag:p|text_align:left|color:rgba(10%2C10%2C10%2C0.6)&#8220; use_theme_fonts=&#8220;yes&#8220;][nectar_btn size=&#8220;large&#8220; button_style=&#8220;see-through-2&#8243; hover_text_color_override=&#8220;#ffffff&#8220; icon_family=&#8220;none&#8220; url=&#8220;mailto:svenbuchheister@yahoo.com&#8220; text=&#8220;Anfrage Teamevent&#8220; margin_top=&#8220;30&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220;&#8230;<\/p>\n","protected":false},"author":16,"featured_media":0,"parent":56,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-60","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unternehmen | Ski Nordisch &amp; Biathlon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unternehmen | Ski Nordisch &amp; Biathlon\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/\" \/>\n<meta property=\"og:site_name\" content=\"Ski Nordisch &amp; Biathlon\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-20T09:34:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/langlaufkurse\\\/unternehmen\\\/\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/langlaufkurse\\\/unternehmen\\\/\",\"name\":\"Unternehmen | Ski Nordisch &amp; Biathlon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#website\"},\"datePublished\":\"2019-11-07T10:28:50+00:00\",\"dateModified\":\"2019-11-20T09:34:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/langlaufkurse\\\/unternehmen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/langlaufkurse\\\/unternehmen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/langlaufkurse\\\/unternehmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SV Kirchzarten\",\"item\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LANGLAUFKURSE\",\"item\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/langlaufkurse\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unternehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/#website\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/\",\"name\":\"Ski Nordisch\",\"description\":\"\",\"alternateName\":\"SV Kirchzarten Ski Nordisch\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svkirchzarten.de\\\/ski-nordisch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unternehmen | Ski Nordisch &amp; Biathlon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/","og_locale":"de_DE","og_type":"article","og_title":"Unternehmen | Ski Nordisch &amp; Biathlon","og_description":"[vc_row type=&#8220;full_width_content&#8220; full_screen_row_position=&#8220;middle&#8220; equal_height=&#8220;yes&#8220; content_placement=&#8220;middle&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; overlay_strength=&#8220;0.3&#8243;][vc_column column_padding=&#8220;no-extra-padding&#8220;...","og_url":"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/","og_site_name":"Ski Nordisch &amp; Biathlon","article_modified_time":"2019-11-20T09:34:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/","url":"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/","name":"Unternehmen | Ski Nordisch &amp; Biathlon","isPartOf":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#website"},"datePublished":"2019-11-07T10:28:50+00:00","dateModified":"2019-11-20T09:34:30+00:00","breadcrumb":{"@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/unternehmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SV Kirchzarten","item":"https:\/\/svkirchzarten.de\/ski-nordisch\/"},{"@type":"ListItem","position":2,"name":"LANGLAUFKURSE","item":"https:\/\/svkirchzarten.de\/ski-nordisch\/langlaufkurse\/"},{"@type":"ListItem","position":3,"name":"Unternehmen"}]},{"@type":"WebSite","@id":"https:\/\/svkirchzarten.de\/ski-nordisch\/#website","url":"https:\/\/svkirchzarten.de\/ski-nordisch\/","name":"Ski Nordisch","description":"","alternateName":"SV Kirchzarten Ski Nordisch","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svkirchzarten.de\/ski-nordisch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:36:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/pages\/60","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":0,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/pages\/60\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/pages\/56"}],"wp:attachment":[{"href":"https:\/\/svkirchzarten.de\/ski-nordisch\/wp-json\/wp\/v2\/media?parent=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}