{"id":1374,"date":"2019-10-10T09:02:33","date_gmt":"2019-10-10T07:02:33","guid":{"rendered":"https:\/\/svkirchzarten.de\/fussball\/?p=1374"},"modified":"2019-10-10T09:09:59","modified_gmt":"2019-10-10T07:09:59","slug":"landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr","status":"publish","type":"post","link":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/","title":{"rendered":"Landesliga 2: SV Au-Wittnau &#8211; SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr)"},"content":{"rendered":"<p><strong>Tobias G\u00f6bel: &#8222;Mit dem Ball f\u00e4llt uns manchmal zu wenig ein&#8220;<\/strong><br \/>\n<strong>Interview zum Spieltag mit Tobias G\u00f6bel, dem Trainer des SV Kirchzarten<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1378 size-medium\" src=\"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/10\/209A0085-290x300.jpg\" alt=\"\" width=\"290\" height=\"300\" srcset=\"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/10\/209A0085-290x300.jpg 290w, https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/10\/209A0085-992x1024.jpg 992w, https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/10\/209A0085-768x793.jpg 768w, https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/10\/209A0085-1487x1536.jpg 1487w, https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/10\/209A0085-280x289.jpg 280w, https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/10\/209A0085.jpg 1922w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/>Acht Spiele, elf Punkte \u2013 der SV Kirchzarten ist durchaus ordentlich in die Saison gestartet. Nachdem seine Mannschaft in der Vorsaison erst auf den allerletzten Dr\u00fccker den Ligaerhalt schaffte, hat Tobias G\u00f6bel in seinem zweiten Jahr als Cheftrainer im Dreisamtal das Tabellenmittelfeld im Blick. G\u00f6bel \u00e4u\u00dfert sich im BZ-Interview unter anderem auch zu eigenen Fehlern, Defiziten seiner Mannschaft und den Gefahren der Liga.<\/p>\n<p><strong>BZ:<\/strong> Ihre Mannschaft ist gut in die Saison gekommen. Noch fehlt etwas die Konstanz. Woran liegt das?<\/p>\n<p><strong>G\u00f6bel:<\/strong> Wir haben eine ganz junge Mannschaft, die sich toll entwickelt. Ich sehe uns auf einem sehr guten Weg, wir m\u00fcssen allerdings noch mehr an uns glauben und unsere guten Trainingsleistungen im Spiel umsetzen. Im Wettkampf fehlt es gerade den ganz jungen Spielern noch am Zutrauen.<\/p>\n<p><strong>BZ:<\/strong> An sich ordentliche 34 Punkte aus 30 Spielen bedeuteten im Vorjahr den sportlichen Abstieg. Wie ordnen Sie Ihre erste Saison als Trainer in Kirchzarten r\u00fcckblickend ein?<\/p>\n<p><strong>G\u00f6bel:<\/strong> Wir hatten im Vorfeld der Saison einen gro\u00dfen Umbruch. Zahlreich Ur-Kirchzartener hatten den Verein verlassen, das war nicht einfach. Auch zu Beginn dieser Saison haben wir wieder entscheidende S\u00e4ulen verloren. Daf\u00fcr sind viele junge Spieler in den Blickpunkt ger\u00fcckt. Wir m\u00fcssen wachsam sein. Der achte Tabellenplatz, den wir aktuell innehaben, l\u00fcgt ein wenig. Wir sollten zusehen, dass der Abstand nach unten w\u00e4chst.<\/p>\n<p><strong>BZ<\/strong>: In welchen Bereichen haben Sie selbst an sich gearbeitet?<\/p>\n<p><strong>G\u00f6bel:<\/strong> Ich habe den Fehler gemacht, zu wenig mit den Spielern zu sprechen. Daran versuche ich zu arbeiten und suche nun vermehrt das Gespr\u00e4ch. Angesichts von einem relativ gro\u00dfen Kader ist das sehr wichtig.<\/p>\n<p><strong>BZ:<\/strong> Welche konkrete Zielsetzung verfolgen Sie mit dem SV Kirchzarten?<\/p>\n<p><strong>G\u00f6bel:<\/strong> Wir wollen weiter den zahlreichen jungen Akteuren im Team das Vertrauen schenken und diese Spieler weiterbringen. Ich denke, im Verein ist das Potential vorhanden sich in den Top-Acht der Landesliga zu etablieren. Es ist dabei besonders wichtig, dass wir unsere Werte behalten und nicht zu Schnellsch\u00fcssen neigen, wenn es mal nicht so l\u00e4uft. Gerade die jungen Spieler brauchen Zeit.<\/p>\n<p><strong>BZ:<\/strong> Wer hat in Ihrer jungen Mannschaft zuletzt den vielleicht gr\u00f6\u00dften Sprung gemacht?<\/p>\n<p><strong>G\u00f6bel:<\/strong> Robin Steiert hat sich zuletzt enorm verbessert. Er hatte in der Vorsaison nicht immer so viele Einsatzzeiten, nun hat er sich zum Stammspieler entwickelt. Auch Ilja Galic hat noch einmal einen gro\u00dfen Sprung gemacht.<\/p>\n<p><strong>BZ:<\/strong> Wo sehen Sie im Spiel Ihrer Mannschaft noch Defizite?<\/p>\n<p><strong>G\u00f6bel:<\/strong> Mit dem Ball f\u00e4llt uns manchmal noch zu wenig ein. Daran gilt es zu arbeiten. Speziell im n\u00e4chsten Spiel beim SV Au-Wittnau bin ich gespannt, wie wir uns pr\u00e4sentieren.<\/p>\n<p><strong>BZ:<\/strong> Was erwarten Sie von der Partie am Freitagabend?<\/p>\n<p><strong>G\u00f6bel:<\/strong> Das wird ein Duell mit einer sehr homogenen und k\u00e4mpferisch starken Mannschaft. In solchen Spielen m\u00fcssen wir noch mehr dagegenhalten. Auf dem kleinen Kunstrasenplatz wird es kein einfaches Spiel f\u00fcr uns. Der Gegner macht es dort sehr gut. Die Mannschaft ist eingespielt und kann mit einem Sieg an uns vorbeiziehen. Wir sind gewarnt.<\/p>\n<p>Quelle: FuPa.net<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tobias G\u00f6bel: &#8222;Mit dem Ball f\u00e4llt uns manchmal zu wenig&#8230;<\/p>\n","protected":false},"author":8,"featured_media":1349,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[8,47,6],"class_list":{"0":"post-1374","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-fussball","8":"tag-erste-mannschaft","9":"tag-saison-2019-2020","10":"tag-sv-kirchzarten"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Landesliga 2: SV Au-Wittnau - SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr) | Fu\u00dfball<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Landesliga 2: SV Au-Wittnau - SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr) | Fu\u00dfball\" \/>\n<meta property=\"og:description\" content=\"Tobias G\u00f6bel: &#8222;Mit dem Ball f\u00e4llt uns manchmal zu wenig...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/\" \/>\n<meta property=\"og:site_name\" content=\"Fu\u00dfball\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-10T07:02:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-10T07:09:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/09\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"117\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Joachim Wei\u00dfer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Joachim Wei\u00dfer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/\"},\"author\":{\"name\":\"Joachim Wei\u00dfer\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#\\\/schema\\\/person\\\/00a2e49eaf4a6c92f3406c7cdd465ac2\"},\"headline\":\"Landesliga 2: SV Au-Wittnau &#8211; SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr)\",\"datePublished\":\"2019-10-10T07:02:33+00:00\",\"dateModified\":\"2019-10-10T07:09:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/\"},\"wordCount\":546,\"publisher\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/09\\\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png\",\"keywords\":[\"Erste Mannschaft\",\"Saison 2019\\\/2020\",\"SV Kirchzarten\"],\"articleSection\":[\"Fu\u00dfball\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/\",\"name\":\"Landesliga 2: SV Au-Wittnau - SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr) | Fu\u00dfball\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/09\\\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png\",\"datePublished\":\"2019-10-10T07:02:33+00:00\",\"dateModified\":\"2019-10-10T07:09:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/09\\\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png\",\"contentUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/09\\\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png\",\"width\":150,\"height\":117},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/2019\\\/10\\\/10\\\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"SV Kirchzarten\",\"item\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Landesliga 2: SV Au-Wittnau &#8211; SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#website\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/\",\"name\":\"SV Kirchzarten - Fu\u00dfball\",\"description\":\"Sport vereint.\",\"publisher\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#organization\"},\"alternateName\":\"SV Kirchzarten - Fu\u00dfball\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#organization\",\"name\":\"Fu\u00dfball\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/sv-kirchzarten-logo.svg\",\"contentUrl\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/sv-kirchzarten-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"Fu\u00dfball\"},\"image\":{\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/#\\\/schema\\\/person\\\/00a2e49eaf4a6c92f3406c7cdd465ac2\",\"name\":\"Joachim Wei\u00dfer\",\"url\":\"https:\\\/\\\/svkirchzarten.de\\\/fussball\\\/author\\\/joachim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Landesliga 2: SV Au-Wittnau - SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr) | Fu\u00dfball","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/","og_locale":"de_DE","og_type":"article","og_title":"Landesliga 2: SV Au-Wittnau - SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr) | Fu\u00dfball","og_description":"Tobias G\u00f6bel: &#8222;Mit dem Ball f\u00e4llt uns manchmal zu wenig...","og_url":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/","og_site_name":"Fu\u00dfball","article_published_time":"2019-10-10T07:02:33+00:00","article_modified_time":"2019-10-10T07:09:59+00:00","og_image":[{"width":150,"height":117,"url":"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/09\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png","type":"image\/png"}],"author":"Joachim Wei\u00dfer","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Joachim Wei\u00dfer","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/#article","isPartOf":{"@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/"},"author":{"name":"Joachim Wei\u00dfer","@id":"https:\/\/svkirchzarten.de\/fussball\/#\/schema\/person\/00a2e49eaf4a6c92f3406c7cdd465ac2"},"headline":"Landesliga 2: SV Au-Wittnau &#8211; SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr)","datePublished":"2019-10-10T07:02:33+00:00","dateModified":"2019-10-10T07:09:59+00:00","mainEntityOfPage":{"@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/"},"wordCount":546,"publisher":{"@id":"https:\/\/svkirchzarten.de\/fussball\/#organization"},"image":{"@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/#primaryimage"},"thumbnailUrl":"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/09\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png","keywords":["Erste Mannschaft","Saison 2019\/2020","SV Kirchzarten"],"articleSection":["Fu\u00dfball"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/","url":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/","name":"Landesliga 2: SV Au-Wittnau - SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr) | Fu\u00dfball","isPartOf":{"@id":"https:\/\/svkirchzarten.de\/fussball\/#website"},"primaryImageOfPage":{"@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/#primaryimage"},"image":{"@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/#primaryimage"},"thumbnailUrl":"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/09\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png","datePublished":"2019-10-10T07:02:33+00:00","dateModified":"2019-10-10T07:09:59+00:00","breadcrumb":{"@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/#primaryimage","url":"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/09\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png","contentUrl":"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2019\/09\/Landesliga-transparenz-beschnitten-300x234-e1568025500381.png","width":150,"height":117},{"@type":"BreadcrumbList","@id":"https:\/\/svkirchzarten.de\/fussball\/2019\/10\/10\/landesliga-2-sv-au-wittnau-sv-kirchzarten-freitag-11-10-2019-1900-uhr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"SV Kirchzarten","item":"https:\/\/svkirchzarten.de\/fussball\/"},{"@type":"ListItem","position":2,"name":"Landesliga 2: SV Au-Wittnau &#8211; SV Kirchzarten (Freitag, 11.10.2019 19:00 Uhr)"}]},{"@type":"WebSite","@id":"https:\/\/svkirchzarten.de\/fussball\/#website","url":"https:\/\/svkirchzarten.de\/fussball\/","name":"SV Kirchzarten - Fu\u00dfball","description":"Sport vereint.","publisher":{"@id":"https:\/\/svkirchzarten.de\/fussball\/#organization"},"alternateName":"SV Kirchzarten - Fu\u00dfball","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/svkirchzarten.de\/fussball\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/svkirchzarten.de\/fussball\/#organization","name":"Fu\u00dfball","url":"https:\/\/svkirchzarten.de\/fussball\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/svkirchzarten.de\/fussball\/#\/schema\/logo\/image\/","url":"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2021\/02\/sv-kirchzarten-logo.svg","contentUrl":"https:\/\/svkirchzarten.de\/fussball\/wp-content\/uploads\/sites\/2\/2021\/02\/sv-kirchzarten-logo.svg","width":1,"height":1,"caption":"Fu\u00dfball"},"image":{"@id":"https:\/\/svkirchzarten.de\/fussball\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/svkirchzarten.de\/fussball\/#\/schema\/person\/00a2e49eaf4a6c92f3406c7cdd465ac2","name":"Joachim Wei\u00dfer","url":"https:\/\/svkirchzarten.de\/fussball\/author\/joachim\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 20:22:25","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/posts\/1374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/comments?post=1374"}],"version-history":[{"count":0,"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/posts\/1374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/media\/1349"}],"wp:attachment":[{"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/media?parent=1374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/categories?post=1374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/svkirchzarten.de\/fussball\/wp-json\/wp\/v2\/tags?post=1374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}